{"id":235,"count":36,"description":"\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 FlowAccount \u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e34\u0e14\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19","link":"https:\/\/flowaccount.com\/blog\/category\/accountant\/","name":"\u0e19\u0e31\u0e01\u0e1a\u0e31\u0e0d\u0e0a\u0e35","slug":"accountant","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/flowaccount.com\/blog\/wp-json\/wp\/v2\/categories\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flowaccount.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/flowaccount.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/flowaccount.com\/blog\/wp-json\/wp\/v2\/posts?categories=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}